{"id":38259,"date":"2024-07-31T10:35:33","date_gmt":"2024-07-31T13:35:33","guid":{"rendered":"https:\/\/crc.org.ar\/w\/?p=38259"},"modified":"2024-07-31T10:35:33","modified_gmt":"2024-07-31T13:35:33","slug":"regatas-arranco-con-el-pie-derecho-el-clausura-del-a-vo-re","status":"publish","type":"post","link":"https:\/\/crc.org.ar\/w\/regatas-arranco-con-el-pie-derecho-el-clausura-del-a-vo-re\/","title":{"rendered":"Regatas arranc\u00f3 con el pie derecho el Clausura del A.Vo.Re."},"content":{"rendered":"\n<p>(Mi\u00e9rcoles 31 de julio de 2024). El segundo semestre en el torneo de la asociaci\u00f3n chaque\u00f1a arranc\u00f3 con buenos resultados para los equipos regatenses de Sub14 y Sub18.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>El fin de semana dio inicio el Torneo Clausura de la Asociaci\u00f3n de V\u00f3ley de Resistencia (A.Vo.Re.) con la primera fecha de la competencia en las categor\u00edas Sub14 y Sub18, donde el Club de Regatas Corrientes obtuvo buenos resultados.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/crc.org.ar\/w\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-30-at-12.43.47.jpeg\" alt=\"\" class=\"wp-image-38260\" srcset=\"https:\/\/crc.org.ar\/w\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-30-at-12.43.47.jpeg 1600w, https:\/\/crc.org.ar\/w\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-30-at-12.43.47-300x225.jpeg 300w, https:\/\/crc.org.ar\/w\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-30-at-12.43.47-768x576.jpeg 768w, https:\/\/crc.org.ar\/w\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-30-at-12.43.47-1536x1152.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure><\/div>\n\n\n<p>En primer lugar, en la categor\u00eda Sub14 en la rama femenina, las regatenses arrancaron con una derrota contra Regatas Resistencia A por 0-2, mientras que despu\u00e9s sumaron dos triunfos frente a Margarita Bel\u00e9n y a San Carlos Relax por 2-0.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"734\" height=\"749\" src=\"https:\/\/crc.org.ar\/w\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-31-at-10.30.27.jpeg\" alt=\"\" class=\"wp-image-38261\" srcset=\"https:\/\/crc.org.ar\/w\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-31-at-10.30.27.jpeg 734w, https:\/\/crc.org.ar\/w\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-31-at-10.30.27-294x300.jpeg 294w\" sizes=\"(max-width: 734px) 100vw, 734px\" \/><\/figure><\/div>\n\n\n<p>En el masculino por su parte fueron tres victorias en tres presentaciones para los Remeros. Frente a Colonia Elisa y San Carlos Relax gan\u00f3 por 2-0, mientras que a Regatas Resistencia fue victoria en tie-break.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/crc.org.ar\/w\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-30-at-12.52.09.jpeg\" alt=\"\" class=\"wp-image-38262\" srcset=\"https:\/\/crc.org.ar\/w\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-30-at-12.52.09.jpeg 1600w, https:\/\/crc.org.ar\/w\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-30-at-12.52.09-300x225.jpeg 300w, https:\/\/crc.org.ar\/w\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-30-at-12.52.09-768x576.jpeg 768w, https:\/\/crc.org.ar\/w\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-30-at-12.52.09-1536x1152.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure><\/div>\n\n\n<p>Por su parte, el Sub18 femenino tambi\u00e9n arranc\u00f3 con una ca\u00edda frente a Sarmiento de Resistencia por 1-2, mientras que despu\u00e9s sum\u00f3 dos triunfos en fila contra el Club C\u00f3rdoba y Regatas Resistencia B en sets corridas.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/crc.org.ar\/w\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-30-at-13.47.50-2048x1536.jpeg\" alt=\"\" class=\"wp-image-38263\" srcset=\"https:\/\/crc.org.ar\/w\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-30-at-13.47.50-2048x1536.jpeg 2048w, https:\/\/crc.org.ar\/w\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-30-at-13.47.50-300x225.jpeg 300w, https:\/\/crc.org.ar\/w\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-30-at-13.47.50-768x576.jpeg 768w, https:\/\/crc.org.ar\/w\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-30-at-13.47.50-1536x1152.jpeg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure><\/div>\n\n\n<p>En cuanto a la rama masculina en dicha categor\u00eda fue la \u00fanica que tuvo en primera fase cuatro duelos. All\u00ed fue derrota en el debut contra Club C\u00f3rdoba 1-2, y luego sum\u00f3 tres victorias en sets corridas contra San Mart\u00edn, Fundaci\u00f3n Corrientes y Regatas Resistencia B.<\/p>\n\n\n\n<p>El certamen se disputa en fase de grupos a dos ruedas, por lo que ahora restar\u00e1 jugar los partidos de vuelta en la segunda fecha, y all\u00ed se definir\u00e1n los clasificados a la fase final.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Mi\u00e9rcoles 31 de julio de 2024). El segundo semestre en el torneo de la asociaci\u00f3n chaque\u00f1a arranc\u00f3 con buenos resultados para los equipos regatenses de Sub14 y Sub18. El fin de semana dio inicio el Torneo Clausura de la Asociaci\u00f3n de V\u00f3ley de Resistencia (A.Vo.Re.) con la primera fecha de la competencia en las categor\u00edas &hellip;<\/p>\n","protected":false},"author":7,"featured_media":38264,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[156,83],"tags":[],"_links":{"self":[{"href":"https:\/\/crc.org.ar\/w\/wp-json\/wp\/v2\/posts\/38259"}],"collection":[{"href":"https:\/\/crc.org.ar\/w\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/crc.org.ar\/w\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/crc.org.ar\/w\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/crc.org.ar\/w\/wp-json\/wp\/v2\/comments?post=38259"}],"version-history":[{"count":1,"href":"https:\/\/crc.org.ar\/w\/wp-json\/wp\/v2\/posts\/38259\/revisions"}],"predecessor-version":[{"id":38265,"href":"https:\/\/crc.org.ar\/w\/wp-json\/wp\/v2\/posts\/38259\/revisions\/38265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/crc.org.ar\/w\/wp-json\/wp\/v2\/media\/38264"}],"wp:attachment":[{"href":"https:\/\/crc.org.ar\/w\/wp-json\/wp\/v2\/media?parent=38259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/crc.org.ar\/w\/wp-json\/wp\/v2\/categories?post=38259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/crc.org.ar\/w\/wp-json\/wp\/v2\/tags?post=38259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}